{"id":4093,"date":"2017-03-27T15:33:30","date_gmt":"2017-03-27T14:33:30","guid":{"rendered":"https:\/\/www.freydis.de\/wordpress\/?page_id=4093"},"modified":"2019-07-18T10:30:55","modified_gmt":"2019-07-18T09:30:55","slug":"wo-berge-segeln","status":"publish","type":"page","link":"https:\/\/www.freydis.de\/wordpress\/buecher\/wo-berge-segeln\/","title":{"rendered":"Wo Berge segeln: Island, Gr\u00f6nland, Spitzbergen"},"content":{"rendered":"<p><a href=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2016\/12\/cover02plus.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3642 alignright\" src=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2016\/12\/cover02plus-640x1024.jpg\" alt=\"Buch: Wo Berge segeln (Band 2)\" width=\"250\" height=\"400\"><\/a>Band 2 (1988) von Heide Wilts Buchserie &#8222;Mit der <em>Freydis<\/em> \u00fcber sieben Meere&#8220;<\/p>\n<p>Die Reisen ins Nordpolarmeer nach Jan Mayen, Gr\u00f6nland und Spitzbergen 1986\/87.<\/p>\n<p>In arktischen Regionen im Schein der Mitternachtssonne und in der Polarnacht: das Buch ist ein Protokoll seglerischer Extremreisen mit allen Sorgen, Hoffnungen und begl\u00fcckenden Erlebnissen, das nebenbei unterhaltsam Wissen vermittelt.<\/p>\n<div class=\"su-spacer\" style=\"height:70px\"><\/div>\n<h2>Zusammenfassung &#8222;Wo Berge segeln&#8220;<\/h2>\n<div class=\"su-expand su-expand-collapsed su-expand-link-style-default\" data-height=\"250\"><div class=\"su-expand-content su-u-trim\" style=\"color:#333333;max-height:250px;overflow:hidden\">Eine &#8222;unstillbare Sehnsucht, die Herz und Seele wie eine Magnetnagel auf die hohen Breitengrade ausrichtet&#8220;, treibt Heide und Erich Wilts immer wieder in die Polargebiete. Zuerst in die Antarktis und nun \u00fcber den 80. Breitengrad hinaus nach Norden. Mit ihrer 15-m-Stahlyacht <em>Freydis<\/em> und wechselnden Crews wird es eine Extremreise, die ihresgleichen sucht.<\/p>\n<p>Von Neufundland geht es mit Rauschefahrt \u00fcber die Labradorsee zur gr\u00f6\u00dften Insel der Erde \u2013 Gr\u00f6nland\u2013, wo Berge segeln und in den Fjorden der jahrtausendealte Atem der Gletscher weht. Dann lockt die &#8222;Bergk\u00f6nigin mit den Eisdiadem&#8220;: Island mit seinen Vulkanen, Geysiren und Sandw\u00fcsten. Und schlie\u00dflich gelingt der <em>Freydis<\/em>, was beispielsweise H. W. Tilmann 1968\/72 viermal vergeblich versuchte und wobei er zwei Schiffe verlor: Sie dringt bis in den Scoresbysund Ostgr\u00f6nlands vor, bedroht von Eis, Nebel und Sturm.<\/p>\n<p>Vor dem n\u00e4her r\u00fcckenden Packeis weichen die Segler nach Jan Mayen aus, der alten Walf\u00e4ngerinsel. Eine besonders harte Etappe wird die \u00dcberquerung des Nordmeeres zum kalten Ende der Welt: Spitzbergen. Trotz des extrem fr\u00fchen Wintereinbruchs sto\u00dfen <em>Freydis<\/em> und ihr Begleitschiff <em>Laga<\/em> dort bis 80 Grad Nord ans Packeis vor. Doch die Schiffe vereisen, auf seinem Tanzboden, der Barentssee, ist der Teufel los&#8230; So bleibt nur die R\u00fcckkehr nach Troms\u00f6 und ein &#8222;da capo&#8220; im n\u00e4chsten Jahr. Und dieser zweite Vorsto\u00df wird zum H\u00f6hepunkt des Besuches: Im Schein der Mitternachtssonne gelingt den Wilts die Umrundung Spitzbergens durch die gef\u00e4hrliche Hinlopenstra\u00dfe.<\/p>\n<p>In der undramatischen, fast lakonischen Sprache der echten Abenteuer erz\u00e4hlt Heide Wilts vom Segeln in einer Natur, die f\u00fcr Eisb\u00e4r und Walross, Robbe und Sturmvogel geschaffen ist, nicht aber f\u00fcr den Menschen. Dennoch fordert diese sie, fasziniert von ihren Sch\u00e4tzen, immer wieder heraus. Deshalb wurde die Arktis zum Schauplatz vieler Trag\u00f6dien f\u00fcr Mensch und Tier, deren Kette bei den Wikingern beginnt und bis zu den \u00d6lsuchern unserer Tage reicht. Parallel zu den eigenen Erlebnissen verfolgt Heide Wilts die Erschlie\u00dfung der besuchten Gebiete bis in die Geschichte zur\u00fcck und l\u00e4sst die Hauptakteure dank eines einmaligen Quellenstudiums am Ort ihrer Taten wieder lebendig werden.<\/p>\n<p>So wollte dies nicht nur das Protokoll einer seglerischen Extremreise sein, sondern auch ein Buch, das unterhaltsam Wissen vermittelt.<\/div><div class=\"su-expand-link su-expand-link-more\" style=\"text-align:center\"><a href=\"javascript:;\" style=\"color:#333;border-color:#333\"><i class=\"sui sui-expand\" style=\"\" aria-label=\"\"><\/i><span style=\"border-color:#333\">Komplette Zusammenfassung anzeigen<\/span><\/a><\/div><div class=\"su-expand-link su-expand-link-less\" style=\"text-align:center\"><a href=\"javascript:;\" style=\"color:#333;border-color:#333\"><i class=\"sui sui-compress\" style=\"\" aria-label=\"\"><\/i><span style=\"border-color:#333\">Komplette Zusammenfassung ausblenden<\/span><\/a><\/div><\/div>\n<div class=\"su-spacer\" style=\"height:70px\"><\/div>\n<h2>Leseprobe &#8222;Wo Berge segeln&#8220;<\/h2>\n<p>Leseprobe aus Kapitel 9&nbsp;&#8222;Alpinistische Akrobatik&#8220; des Buches:<\/p>\n<a href=\"https:\/\/www.freydis.de\/wordpress\/buecher\/wo-berge-segeln\/leseprobe\/\" class=\"su-button su-button-style-default\" style=\"color:#fff;background-color:#ef332d;border-color:#c02924;border-radius:5px\" target=\"_self\" title=\"Leseprobe\"><span style=\"color:#fff;padding:7px 20px;font-size:16px;line-height:24px;border-color:#f4716c;border-radius:5px;text-shadow:none\"><i class=\"sui sui-book\" style=\"font-size:16px;color:#fff\"><\/i> Leseprobe<\/span><\/a>\n<div class=\"su-spacer\" style=\"height:20px\"><\/div>\n<div class=\"su-spacer\" style=\"height:70px\"><\/div>\n<h2 id=\"kaufen\">&#8222;Wo Berge segeln&#8220; kaufen<\/h2>\n<div class=\"alignright\"><a href=\"#apple\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3827\" title=\"E-Book im Apple iBookstore kaufen\" src=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/apple_ibooks_logo.png\" alt=\"\" width=\"112\" height=\"40\"><\/a><br \/>\n<a href=\"#amazon\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3826\" title=\"E-Book im Amazon Kindle-Shop kaufen\" src=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/amazon_kindle_logo.png\" alt=\"\" width=\"190\" height=\"40\" srcset=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/amazon_kindle_logo.png 474w, https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/amazon_kindle_logo-300x63.png 300w\" sizes=\"auto, (max-width: 190px) 100vw, 190px\" \/><\/a><br \/>\n<a href=\"#tolino\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3836\" title=\"E-Book im Tolino Handel kaufen\" src=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/tolino_logo.png\" alt=\"\" width=\"104\" height=\"40\"><\/a><\/div>\n<p>Das Buch gibt es als gedruckte Ausgabe f\u00fcr 24,80 \u20ac und als E-Book in zwei Ausf\u00fchrungen:<\/p>\n<ul>\n<li>normalbebildert (Basic-Version) f\u00fcr 9,99 \u20ac<\/li>\n<li>als Edition+ mit \u00fcber 250 Farbfotos f\u00fcr 14,99 \u20ac<\/li>\n<\/ul>\n<div class=\"su-spacer\" style=\"height:20px\"><\/div>\n<div class=\"su-tabs su-tabs-style-default su-tabs-mobile-stack\" data-active=\"2\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-tabs-nav\"><span class=\"\" data-anchor=\"print\" data-url=\"\" data-target=\"blank\" tabindex=\"0\" role=\"button\">Gedruckte Ausgabe<\/span><span class=\"\" data-anchor=\"apple\" data-url=\"\" data-target=\"blank\" tabindex=\"0\" role=\"button\">Apple iBooks<\/span><span class=\"\" data-anchor=\"amazon\" data-url=\"\" data-target=\"blank\" tabindex=\"0\" role=\"button\">Amazon Kindle<\/span><span class=\"\" data-anchor=\"tolino\" data-url=\"\" data-target=\"blank\" tabindex=\"0\" role=\"button\">Tolino<\/span><\/div><div class=\"su-tabs-panes\"><div class=\"su-tabs-pane su-u-clearfix su-u-trim\" data-title=\"Gedruckte Ausgabe\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-4102 size-medium\" src=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/Cover_Wo_Berge_Segeln-206x300.jpg\" alt=\"Cover: Wo Berge segeln\" width=\"206\" height=\"300\" srcset=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/Cover_Wo_Berge_Segeln-206x300.jpg 206w, https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/Cover_Wo_Berge_Segeln.jpg 297w\" sizes=\"auto, (max-width: 206px) 100vw, 206px\" \/>Das gedruckte Buch &#8222;Wo Berge segeln&#8220; kann direkt bei&nbsp;Heide Wilts bestellt werden. Bitte benutzen Sie dazu das unten stehende Bestellformular.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-3882 size-full\" src=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/freydis-bord-stempel.png\" alt=\"\" width=\"117\" height=\"122\"><\/p>\n<p>Alle B\u00fccher mit Bordstempel und handsigniert, auf Wunsch auch mit Widmung (bitte spezifizieren).<\/p>\n<p>Sie erhalten \u00fcber uns alle B\u00fccher, auch die im Handel vergriffenen.<\/p>\n<p>Kosten: 24,80 \u20ac (versandkostenfrei)<\/p>\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f3942-o1\" lang=\"de-DE\" dir=\"ltr\" data-wpcf7-id=\"3942\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/wordpress\/wp-json\/wp\/v2\/pages\/4093#wpcf7-f3942-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Kontaktformular\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"3942\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"de_DE\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f3942-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<p><br \/>\nW\u00e4hlen Sie ein oder mehrere B\u00fccher:<br \/>\n<label for=\"freydis-book\">Buch<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"freydis-book\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" id=\"freydis-book\" aria-required=\"true\" aria-invalid=\"false\" multiple=\"multiple\" name=\"freydis-book[]\"><option value=\"Im Sturm - Segeln im Extremwetter, Band I+II (29,80 \u20ac)\">Im Sturm - Segeln im Extremwetter, Band I+II (29,80 \u20ac)<\/option><option value=\"Band 11: Eskapade \u2013 Von Japan durch die Nordwestpassage (24,80 \u20ac)\">Band 11: Eskapade \u2013 Von Japan durch die Nordwestpassage (24,80 \u20ac)<\/option><option value=\"Band 10: K. O. \u2013 und nochmal gepackt! (24,80 \u20ac)\">Band 10: K. O. \u2013 und nochmal gepackt! (24,80 \u20ac)<\/option><option value=\"Band 9: Alaska \u2013 Japan (24,80 \u20ac)\">Band 9: Alaska \u2013 Japan (24,80 \u20ac)<\/option><option value=\"Band 8: Von Australien nach Europa (Vorbestellung)\">Band 8: Von Australien nach Europa (Vorbestellung)<\/option><option value=\"Band 7: Inseln jenseits der Zeit (15,00 \u20ac)\">Band 7: Inseln jenseits der Zeit (15,00 \u20ac)<\/option><option value=\"Band 6: Wilder Stiller Ozean (24,80 \u20ac)\">Band 6: Wilder Stiller Ozean (24,80 \u20ac)<\/option><option value=\"Band 5: Segeln ans Ende der Welt (24,80 \u20ac)\">Band 5: Segeln ans Ende der Welt (24,80 \u20ac)<\/option><option value=\"Band 4: Auf der Route der Albatrosse (24,80 \u20ac)\">Band 4: Auf der Route der Albatrosse (24,80 \u20ac)<\/option><option value=\"Band 3: Gestrandet in der wei\u00dfen H\u00f6lle (15,00 \u20ac)\">Band 3: Gestrandet in der wei\u00dfen H\u00f6lle (15,00 \u20ac)<\/option><option value=\"Band 2: Wo Berge segeln (24,80 \u20ac)\">Band 2: Wo Berge segeln (24,80 \u20ac)<\/option><option value=\"Band 1: Weit im Norden liegt Kap Hoorn (24,80 \u20ac)\">Band 1: Weit im Norden liegt Kap Hoorn (24,80 \u20ac)<\/option><option value=\"Text-Bildband: Sternstunden auf allen Ozeanen (40,00 \u20ac)\">Text-Bildband: Sternstunden auf allen Ozeanen (40,00 \u20ac)<\/option><option value=\"Text-Bildband: Segelziele voller Wunder (28,00 \u20ac)\">Text-Bildband: Segelziele voller Wunder (28,00 \u20ac)<\/option><option value=\"Text-Bildband: Segelabenteuer im S\u00fcdpazifik (28,00 \u20ac)\">Text-Bildband: Segelabenteuer im S\u00fcdpazifik (28,00 \u20ac)<\/option><option value=\"Text-Bildband: Inseln voller Magie (28,00 \u20ac)\">Text-Bildband: Inseln voller Magie (28,00 \u20ac)<\/option><\/select><\/span>\n<\/p>\n<p class=\"freydis-half\"><br \/>\n<label for=\"freydis-name\">Vor- und Nachname<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"freydis-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" id=\"freydis-name\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Vor- und Nachname\" value=\"\" type=\"text\" name=\"freydis-name\" \/><\/span>\n<\/p>\n<p class=\"freydis-half\"><br \/>\n<label for=\"freydis-street\">Stra\u00dfe \/ Nr.<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"freydis-street\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" id=\"freydis-street\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Stra\u00dfe \/ Nr.\" value=\"\" type=\"text\" name=\"freydis-street\" \/><\/span>\n<\/p>\n<p class=\"freydis-half\"><br \/>\n<label for=\"freydis-plz\">PLZ<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"freydis-plz\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" id=\"freydis-plz\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"PLZ\" value=\"\" type=\"text\" name=\"freydis-plz\" \/><\/span>\n<\/p>\n<p class=\"freydis-half\"><br \/>\n<label for=\"freydis-city\">Ort<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"freydis-city\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" id=\"freydis-city\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Ort\" value=\"\" type=\"text\" name=\"freydis-city\" \/><\/span>\n<\/p>\n<p class=\"freydis-half\"><br \/>\n<label for=\"freydis-email\">E-Mail<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"freydis-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" id=\"freydis-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-Mail (f\u00fcr die Bestellbest\u00e4tigung)\" value=\"\" type=\"email\" name=\"freydis-email\" \/><\/span>\n<\/p>\n<p class=\"freydis-half\"><br \/>\n<label for=\"freydis-telephone\">Telefon<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"freydis-telephone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-text wpcf7-validates-as-tel\" id=\"freydis-telephone\" aria-invalid=\"false\" placeholder=\"Telefon (optional, f\u00fcr R\u00fcckfragen)\" value=\"\" type=\"tel\" name=\"freydis-telephone\" \/><\/span>\n<\/p>\n<p class=\"freydis-full\"><br \/>\nAngaben zu Widmungen, Anzahl pro Band, sonstige Bemerkungen, etc. (optional):<br \/>\n<label for=\"freydis-message\">Bemerkungen<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"freydis-message\"><textarea cols=\"40\" rows=\"5\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" id=\"freydis-message\" aria-invalid=\"false\" placeholder=\"z.B.: Band 3: 2x, in einem Exemplar folgende Widmung: ...\" name=\"freydis-message\"><\/textarea><\/span><br \/>\nAlle Buchbestellungen sind versandkostenfrei!\n<\/p>\n<p class=\"freydis-auto-width freydis-center\"><br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner freydis-submit\" id=\"freydis-submit\" type=\"submit\" value=\"Kostenpflichtig bestellen\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n<\/div>\n<div class=\"su-tabs-pane su-u-clearfix su-u-trim\" data-title=\"Apple iBooks\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-3827\" src=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/apple_ibooks_logo.png\" alt=\"\" width=\"180\" height=\"65\">Bei Apple gibt es das E-Book &#8222;Wo Berge segeln&#8220; in der Edition+ im iBookstore. Es ist auf Grund des statischen Designs besonders ansprechend formatiert.<\/p>\n<p>Es kann direkt \u00fcber die vorinstallierten Apps iBooks oder iTunes gekauft werden und mit iBooks gelesen werden (nur f\u00fcr macOS).<\/p>\n<div class=\"su-button-center\"><a href=\"https:\/\/itunes.apple.com\/de\/book\/id989563003\" class=\"su-button su-button-style-default su-button-wide\" style=\"color:#111;background-color:#febd69;border-color:#cc9854;border-radius:5px\" target=\"_blank\" rel=\"nofollow\" title=\"E-Book direkt im Apple iBookstore kaufen\"><span style=\"color:#111;padding:7px 20px;font-size:16px;line-height:24px;border-color:#ffd196;border-radius:5px;text-shadow:none\"><i class=\"sui sui-book\" style=\"font-size:16px;color:#111\"><\/i> Edition+ f\u00fcr 14,99 \u20ac im Apple iBookstore&nbsp;kaufen<\/span><\/a><\/div>\n<\/div>\n<div class=\"su-tabs-pane su-u-clearfix su-u-trim\" data-title=\"Amazon Kindle\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-3826\" src=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/amazon_kindle_logo.png\" alt=\"\" width=\"308\" height=\"65\" srcset=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/amazon_kindle_logo.png 474w, https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/amazon_kindle_logo-300x63.png 300w\" sizes=\"auto, (max-width: 308px) 100vw, 308px\" \/>Im Amazon Kindle-Shop gibt es das E-Book &#8222;Wo Berge segeln&#8220;&nbsp;von Heide Wilts in den zwei Ausf\u00fchrungen: Basic und als Edition+.<\/p>\n<p>Es kann direkt bei Amazon gekauft werden und mit einem <a href=\"https:\/\/www.amazon.de\/gp\/product\/B0186FESVC\/ref=as_li_ss_tl?ie=UTF8&amp;linkCode=ll1&amp;tag=freydis-21&amp;linkId=14cd773844e68274bfcd73a8be4b008c\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">Amazon Kindle eReader<\/a> oder der <a href=\"https:\/\/www.amazon.de\/gp\/digital\/fiona\/kcp-landing-page\/ref=as_li_ss_tl?ie=UTF8&amp;linkCode=ll2&amp;tag=freydis-21&amp;linkId=800dcabba6320af50f0ce960050867be\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">gratis Kindle Lese-App<\/a> gelesen werden.<\/p>\n<div class=\"su-button-center\"><a href=\"https:\/\/www.amazon.de\/dp\/B00XO12YME\/ref=as_li_ss_tl?ie=UTF8&#038;linkCode=ll1&#038;tag=freydis-21&#038;linkId=abf9b6eaac7873302ec0266d5797f6d6\" class=\"su-button su-button-style-default su-button-wide\" style=\"color:#111;background-color:#febd69;border-color:#cc9854;border-radius:5px\" target=\"_blank\" rel=\"nofollow\" title=\"E-Book direkt bei Amazon kaufen\"><span style=\"color:#111;padding:7px 20px;font-size:16px;line-height:24px;border-color:#ffd196;border-radius:5px;text-shadow:none\"><i class=\"sui sui-book\" style=\"font-size:16px;color:#111\"><\/i> Edition+ f\u00fcr 14,99 \u20ac bei Amazon kaufen<\/span><\/a><\/div>\n<div class=\"su-button-center\"><a href=\"https:\/\/www.amazon.de\/dp\/B00T6305KC\/ref=as_li_ss_tl?ie=UTF8&#038;linkCode=ll1&#038;tag=freydis-21&#038;linkId=fbc7d790720a321b0823e00a2cdc82cc\" class=\"su-button su-button-style-default su-button-wide\" style=\"color:#111;background-color:#febd69;border-color:#cc9854;border-radius:5px\" target=\"_blank\" rel=\"nofollow\" title=\"E-Book direkt bei Amazon kaufen\"><span style=\"color:#111;padding:7px 20px;font-size:16px;line-height:24px;border-color:#ffd196;border-radius:5px;text-shadow:none\"><i class=\"sui sui-book\" style=\"font-size:16px;color:#111\"><\/i> Basic-Version f\u00fcr 9,99 \u20ac bei Amazon kaufen<\/span><\/a><\/div>\n<\/div>\n<div class=\"su-tabs-pane su-u-clearfix su-u-trim\" data-title=\"Tolino\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-3836\" title=\"E-Book im Tolino Handel verf\u00fcgbar\" src=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/tolino_logo.png\" alt=\"\" width=\"170\" height=\"65\">Das E-Book &#8222;Wo Berge segeln&#8220; von Heide Wilts ist bei den Tolino H\u00e4ndlern in verf\u00fcgbar. Es steht in den beiden Ausf\u00fchrungen Basic&nbsp;und als Edition+ zur Verf\u00fcgung.<\/p>\n<p>Es kann bei allen H\u00e4ndlern der Tolino Allianz erworben werden und auf allen Ger\u00e4ten gelesen werden, die epub-f\u00e4hig sind (z.B.&nbsp;auf den <a href=\"http:\/\/mytolino.de\/tolino-ebook-reader-vergleich\/\" target=\"_blank\" rel=\"noopener noreferrer\">tolino<\/a>&nbsp;oder Sony Readern). Au\u00dferdem kann es mit der <a href=\"http:\/\/mytolino.de\/tolino-app\/gratis-tolino-lese-app-ebooks-lesen-hoerbuecher-hoeren\/\" target=\"_blank\" rel=\"noopener noreferrer\">gratis tolino Lese-App<\/a>&nbsp;(Smartphone und Tablet) oder dem tolino Webreader direkt im Webbrowser gelesen werden.<\/p>\n<p>Bestellen sie direkt bei Ihrer Lieblingsbuchhandlung:<\/p>\n<div class=\"su-accordion su-u-trim\">\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-chevron\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>Edition+ f\u00fcr 14,99 \u20ac kaufen<\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<p>Kaufen Sie das E-Book in der Edition+ bei einem Tolino H\u00e4ndler. Einfach ein H\u00e4ndler-Logo ausw\u00e4hlen um bei dem jeweiligen Anbieter zu bestellen:<\/p>\n<p><a href=\"http:\/\/www.thalia.de\/shop\/ebooks\/suchartikel\/ID44247661.html\" target=\"_blank\" rel=\"nofollow noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-3835\" title=\"E-Book direkt bei Thalia kaufen\" src=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/thalia_logo-300x68.png\" alt=\"\" width=\"168\" height=\"38\" srcset=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/thalia_logo-300x68.png 300w, https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/thalia_logo.png 440w\" sizes=\"auto, (max-width: 168px) 100vw, 168px\" \/><\/a><a href=\"https:\/\/www.weltbild.de\/artikel\/ebook\/wo-berge-segeln-edition_21090451-1\" target=\"_blank\" rel=\"nofollow noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-3837\" title=\"E-Book direkt bei Weltbild kaufen\" src=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/weltbild_logo-300x73.png\" alt=\"\" width=\"168\" height=\"41\" srcset=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/weltbild_logo-300x73.png 300w, https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/weltbild_logo.png 413w\" sizes=\"auto, (max-width: 168px) 100vw, 168px\" \/><\/a><a href=\"http:\/\/www.ebook.de\/de\/product\/25352402\/heide_wilts_wo_berge_segeln_edition.html\" target=\"_blank\" rel=\"nofollow noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-3830\" title=\"E-Book direkt bei eBook.de kaufen\" src=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/ebook_de_logo.png\" alt=\"\" width=\"168\" height=\"44\" srcset=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/ebook_de_logo.png 379w, https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/ebook_de_logo-300x79.png 300w\" sizes=\"auto, (max-width: 168px) 100vw, 168px\" \/><\/a> <a href=\"http:\/\/www.hugendubel.de\/de\/ebook\/heide_wilts-wo_berge_segeln_edition-25352402-produkt-details.html\" target=\"_blank\" rel=\"nofollow noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-3831\" title=\"E-Book direkt bei Hugendubel kaufen\" src=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/hugendubel_logo.png\" alt=\"\" width=\"168\" height=\"30\" srcset=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/hugendubel_logo.png 559w, https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/hugendubel_logo-300x54.png 300w\" sizes=\"auto, (max-width: 168px) 100vw, 168px\" \/><\/a><a href=\"https:\/\/www.osiander.de\/webdb\/index.cfm?osiaction=details&amp;id=TMEDT0152.9783981734836\" target=\"_blank\" rel=\"nofollow noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-3834\" title=\"E-Book direkt bei Osiander kaufen\" src=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/osiander_logo-300x54.png\" alt=\"\" width=\"168\" height=\"30\" srcset=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/osiander_logo-300x54.png 300w, https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/osiander_logo.png 551w\" sizes=\"auto, (max-width: 168px) 100vw, 168px\" \/><\/a><a href=\"http:\/\/www.buecher.de\/shop\/orte--laender\/wo-berge-segeln-edition-ebook-epub\/wilts-heide\/products_products\/detail\/prod_id\/44111942\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-3829\" title=\"E-Book direkt bei b\u00fccher.de kaufen\" src=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/buecher_de_logo.png\" alt=\"\" width=\"168\" height=\"40\" srcset=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/buecher_de_logo.png 415w, https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/buecher_de_logo-300x72.png 300w\" sizes=\"auto, (max-width: 168px) 100vw, 168px\" \/><\/a><a href=\"http:\/\/www.mayersche.de\/Wo-Berge-segeln-Edition-ebook-Heide-Wilts.html\" target=\"_blank\" rel=\"nofollow noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-3832\" title=\"E-Book direkt bei Mayersche kaufen\" src=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/mayersche_logo.png\" alt=\"\" width=\"168\" height=\"79\"><\/a><\/p>\n<\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-chevron su-spoiler-closed\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>Basic-Version f\u00fcr 9,99 \u20ac kaufen<\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<p>Kaufen Sie das E-Book in der Basic-Version&nbsp;bei einem Tolino H\u00e4ndler. Einfach ein H\u00e4ndler-Logo ausw\u00e4hlen um bei dem jeweiligen Anbieter zu bestellen:<\/p>\n<p><a href=\"http:\/\/www.thalia.de\/shop\/ebooks\/suchartikel\/ID43233862.html\" target=\"_blank\" rel=\"nofollow noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-3835\" title=\"E-Book direkt bei Thalia kaufen\" src=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/thalia_logo-300x68.png\" alt=\"\" width=\"168\" height=\"38\" srcset=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/thalia_logo-300x68.png 300w, https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/thalia_logo.png 440w\" sizes=\"auto, (max-width: 168px) 100vw, 168px\" \/><\/a><a href=\"https:\/\/www.weltbild.de\/artikel\/ebook\/wo-berge-segeln_20644331-1\" target=\"_blank\" rel=\"nofollow noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-3837\" title=\"E-Book direkt bei Weltbild kaufen\" src=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/weltbild_logo-300x73.png\" alt=\"\" width=\"168\" height=\"41\" srcset=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/weltbild_logo-300x73.png 300w, https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/weltbild_logo.png 413w\" sizes=\"auto, (max-width: 168px) 100vw, 168px\" \/><\/a><a href=\"http:\/\/www.ebook.de\/de\/product\/24461225\/heide_wilts_wo_berge_segeln.html\" target=\"_blank\" rel=\"nofollow noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-3830\" title=\"E-Book direkt bei eBook.de kaufen\" src=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/ebook_de_logo.png\" alt=\"\" width=\"168\" height=\"44\" srcset=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/ebook_de_logo.png 379w, https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/ebook_de_logo-300x79.png 300w\" sizes=\"auto, (max-width: 168px) 100vw, 168px\" \/><\/a> <a href=\"http:\/\/www.hugendubel.de\/de\/ebook\/heide_wilts-wo_berge_segeln-24461225-produkt-details.html\" target=\"_blank\" rel=\"nofollow noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-3831\" title=\"E-Book direkt bei Hugendubel kaufen\" src=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/hugendubel_logo.png\" alt=\"\" width=\"168\" height=\"30\" srcset=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/hugendubel_logo.png 559w, https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/hugendubel_logo-300x54.png 300w\" sizes=\"auto, (max-width: 168px) 100vw, 168px\" \/><\/a><a href=\"https:\/\/www.osiander.de\/webdb\/index.cfm?osiaction=details&amp;id=LBDA25200862\" target=\"_blank\" rel=\"nofollow noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-3834\" title=\"E-Book direkt bei Osiander kaufen\" src=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/osiander_logo-300x54.png\" alt=\"\" width=\"168\" height=\"30\" srcset=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/osiander_logo-300x54.png 300w, https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/osiander_logo.png 551w\" sizes=\"auto, (max-width: 168px) 100vw, 168px\" \/><\/a><a href=\"http:\/\/www.buecher.de\/shop\/krimi--thriller\/wo-berge-segeln-ebook-epub\/wilts-heide\/products_products\/detail\/prod_id\/43168830\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-3829\" title=\"E-Book direkt bei b\u00fccher.de kaufen\" src=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/buecher_de_logo.png\" alt=\"\" width=\"168\" height=\"40\" srcset=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/buecher_de_logo.png 415w, https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/buecher_de_logo-300x72.png 300w\" sizes=\"auto, (max-width: 168px) 100vw, 168px\" \/><\/a><a href=\"http:\/\/www.mayersche.de\/Wo-Berge-segeln-ebook-Heide-Wilts.html\" target=\"_blank\" rel=\"nofollow noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-3832\" title=\"E-Book direkt bei Mayersche kaufen\" src=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/mayersche_logo.png\" alt=\"\" width=\"168\" height=\"79\"><\/a><\/p>\n<\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-chevron su-spoiler-closed\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>Weitere Buchhandlungen<\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<p>Finden Sie weitere Tolino Buchhandlungen&nbsp;&#8211; auch bei Ihnen in der N\u00e4he:<\/p>\n<p><a href=\"http:\/\/www.buchhandlung.de\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3833\" title=\"Finden Sie Ihre Lieblingsbuchhandlung auf Buchhandlung.de\" src=\"https:\/\/www.freydis.de\/wordpress\/wp-content\/uploads\/2017\/03\/meine_buchhandlung_logo.png\" alt=\"\" width=\"175\" height=\"45\"><\/a><\/p>\n<\/div><\/div>\n<\/div>\n<\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Band 2 (1988) von Heide Wilts Buchserie &#8222;Mit der Freydis \u00fcber sieben Meere&#8220; Die Reisen ins Nordpolarmeer nach Jan Mayen, Gr\u00f6nland und Spitzbergen 1986\/87. In arktischen Regionen im Schein der Mitternachtssonne und in der Polarnacht: das Buch ist ein Protokoll &hellip; <a href=\"https:\/\/www.freydis.de\/wordpress\/buecher\/wo-berge-segeln\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"parent":3708,"menu_order":20,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4093","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.freydis.de\/wordpress\/wp-json\/wp\/v2\/pages\/4093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.freydis.de\/wordpress\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.freydis.de\/wordpress\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.freydis.de\/wordpress\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.freydis.de\/wordpress\/wp-json\/wp\/v2\/comments?post=4093"}],"version-history":[{"count":10,"href":"https:\/\/www.freydis.de\/wordpress\/wp-json\/wp\/v2\/pages\/4093\/revisions"}],"predecessor-version":[{"id":5567,"href":"https:\/\/www.freydis.de\/wordpress\/wp-json\/wp\/v2\/pages\/4093\/revisions\/5567"}],"up":[{"embeddable":true,"href":"https:\/\/www.freydis.de\/wordpress\/wp-json\/wp\/v2\/pages\/3708"}],"wp:attachment":[{"href":"https:\/\/www.freydis.de\/wordpress\/wp-json\/wp\/v2\/media?parent=4093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}